{"id":796,"date":"2015-10-23T13:00:40","date_gmt":"2015-10-23T12:00:40","guid":{"rendered":"https:\/\/startit.qodeinteractive.com\/elementor\/?page_id=796"},"modified":"2020-03-26T10:24:21","modified_gmt":"2020-03-26T10:24:21","slug":"gallery-style-with-space","status":"publish","type":"page","link":"https:\/\/startit.qodeinteractive.com\/elementor\/gallery-style-with-space\/","title":{"rendered":"Gallery Style With Space"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"796\" class=\"elementor elementor-796\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21e14786 qodef_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"21e14786\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45b374ce\" data-id=\"45b374ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3927be4 elementor-widget elementor-widget-qodef_portfolio_list\" data-id=\"3927be4\" data-element_type=\"widget\" data-widget_type=\"qodef_portfolio_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class = \"qodef-portfolio-list-holder-outer qodef-ptf-gallery qodef-ptf-gallery-space qodef-ptf-three-columns qodef-ptf-load-more qodef-ptf-has-filter\" data-next-page= 2 data-type= gallery-space data-columns= three data-order-by= date data-order= ASC data-number= 12 data-filter= yes data-filter-order-by= name data-category= all data-show-load-more= yes data-title-tag= h5 data-max-num-pages = 2><div class = \"qodef-portfolio-filter-holder\">\n\t<div class = \"qodef-portfolio-filter-holder-inner\">\n\t\t\t\t<ul>\n\t\t\t\n\t\t\t<li data-class=\"filter_1436258513\" class=\"filter_1436258513\" data-filter=\"all\"><span>All<\/span><\/li>\n\t\t\t\n\t\t\t\t\t\t\t<li data-class=\"filter_1436258513\" class=\"filter_1436258513\" data-filter = \".portfolio_category_10\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tBusiness\t\t\t\t\t<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li data-class=\"filter_1436258513\" class=\"filter_1436258513\" data-filter = \".portfolio_category_7\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tMarketing\t\t\t\t\t<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li data-class=\"filter_1436258513\" class=\"filter_1436258513\" data-filter = \".portfolio_category_12\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tMedia\t\t\t\t\t<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li data-class=\"filter_1436258513\" class=\"filter_1436258513\" data-filter = \".portfolio_category_11\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tPlatform\t\t\t\t\t<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li data-class=\"filter_1436258513\" class=\"filter_1436258513\" data-filter = \".portfolio_category_8\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tResearch\t\t\t\t\t<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li data-class=\"filter_1436258513\" class=\"filter_1436258513\" data-filter = \".portfolio_category_9\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tStartup\t\t\t\t\t<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul> \n\t\t\t<\/div>\t\t\n<\/div><div class = \"qodef-portfolio-list-holder clearfix\" >\n<article class=\"qodef-portfolio-item mix portfolio_category_10 portfolio_category_7\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/office-management-systems\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-office-management-systems-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-office-management-systems-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-office-management-systems-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-office-management-systems-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-office-management-systems-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-office-management-systems.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tOffice Management Systems\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Business<\/span> <span>\/<\/span> <span>Marketing<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_12 portfolio_category_11\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/new-trends-in-seo-analytics\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-seo-and-analytics-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-seo-and-analytics-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-seo-and-analytics-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-seo-and-analytics-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-seo-and-analytics-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-seo-and-analytics.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tNew Trends In SEO &#038; Analytics\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Media<\/span> <span>\/<\/span> <span>Platform<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_8 portfolio_category_9\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/app-update-rebrand\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-app-update-and-rebrand-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-app-update-and-rebrand-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-app-update-and-rebrand-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-app-update-and-rebrand-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-app-update-and-rebrand-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-app-update-and-rebrand.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tApp Update &#038; Rebrand\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Research<\/span> <span>\/<\/span> <span>Startup<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_10 portfolio_category_7\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/the-tablet-app-of-the-future\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-the-tablet-app-of-the-future-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-the-tablet-app-of-the-future-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-the-tablet-app-of-the-future-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-the-tablet-app-of-the-future-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-the-tablet-app-of-the-future-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-the-tablet-app-of-the-future.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tThe Tablet App Of The Future\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Business<\/span> <span>\/<\/span> <span>Marketing<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_12 portfolio_category_11\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/big-data-goes-global\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-big-data-goes-global-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-big-data-goes-global-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-big-data-goes-global-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-big-data-goes-global-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-big-data-goes-global-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-big-data-goes-global.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tBig Data Goes Global\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Media<\/span> <span>\/<\/span> <span>Platform<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_10 portfolio_category_7\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/new-findings-in-responsive-testing\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-findings-in-responsive-testing-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-findings-in-responsive-testing-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-findings-in-responsive-testing-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-findings-in-responsive-testing-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-findings-in-responsive-testing-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-findings-in-responsive-testing.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tNew Findings In Testing\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Business<\/span> <span>\/<\/span> <span>Marketing<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_12 portfolio_category_11\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/millenials-research-2015\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-millenials-research-2015-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-millenials-research-2015-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-millenials-research-2015-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-millenials-research-2015-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-millenials-research-2015-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-millenials-research-2015.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tMillenials Research 2015\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Media<\/span> <span>\/<\/span> <span>Platform<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_8 portfolio_category_9\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/new-trends-in-social-media\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-social-media-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-social-media-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-social-media-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-social-media-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-social-media-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-new-trends-in-social-media.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tNew Trends In Social Media\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Research<\/span> <span>\/<\/span> <span>Startup<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_10 portfolio_category_7\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/digital-planning\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-digital-planning-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-digital-planning-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-digital-planning-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-digital-planning-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-digital-planning-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-digital-planning.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tDigital Planning\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Business<\/span> <span>\/<\/span> <span>Marketing<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_12 portfolio_category_11\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/sustainable-mobile-app\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-mobile-app-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-mobile-app-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-mobile-app-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-mobile-app-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-mobile-app-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-mobile-app.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tSustainable Mobile App\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Media<\/span> <span>\/<\/span> <span>Platform<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_10 portfolio_category_7\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/sustainable-seo-research\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-seo-research-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-seo-research-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-seo-research-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-seo-research-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-seo-research-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-sustainable-seo-research.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tSustainable SEO Research\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Business<\/span> <span>\/<\/span> <span>Marketing<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n\n<article class=\"qodef-portfolio-item mix portfolio_category_12 portfolio_category_11\" >\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/startit.qodeinteractive.com\/elementor\/portfolio-item\/teamwork-training\/\" target=\"_self\"><\/a>\n\t<div class = \"qodef-item-image-holder\">\n\t<div class=\"qodef-portfolio-shader\"><\/div>\t\n\t<img width=\"800\" height=\"600\" src=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-teamwork-training-800x600.jpg\" class=\"attachment-qode_startit_landscape size-qode_startit_landscape wp-post-image\" alt=\"image\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-teamwork-training-800x600.jpg 800w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-teamwork-training-600x449.jpg 600w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-teamwork-training-300x224.jpg 300w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-teamwork-training-768x575.jpg 768w, https:\/\/startit.qodeinteractive.com\/elementor\/wp-content\/uploads\/2015\/10\/p-teamwork-training.jpg 1100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\n\t<\/div>\n\t<div class=\"qodef-item-text-overlay\">\n\t\t<div class=\"qodef-item-text-overlay-inner\">\n\t\t\t<div class=\"qodef-item-text-holder\">\n\t\t\t\t<h5 class=\"qodef-item-title\">\n\t\t\t\t\tTeamwork Training\t\t\t\t<\/h5>\t\n\t\t\t\t<div class=\"qodef-ptf-category-holder\"><span>Media<\/span> <span>\/<\/span> <span>Platform<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\t\n\t<\/div>\n<\/article>\n\n<div class='qodef-filler'><\/div>\n<div class='qodef-filler'><\/div>\n<div class='qodef-filler'><\/div>\n<\/div>\t<div class=\"qodef-ptf-list-paging\">\n\t\t<span class=\"qodef-ptf-list-load-more\">\n\t\t\t<a href=\"\" target=\"_self\"  class=\"qodef-btn qodef-btn-medium qodef-btn-default\"  >        <span class=\"qodef-btn-text\">Show more<\/span>    <span class=\"qodef-btn-text-icon\"><\/span><\/a>\t\t<\/span>\n\t<\/div>\n\t<input type=\"hidden\" id=\"qodef_ptf_load_more_nonce_4186\" name=\"qodef_ptf_load_more_nonce_4186\" value=\"9040134d5e\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/elementor\/wp-json\/wp\/v2\/pages\/796\" \/><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>All Business Marketing Media Platform Research Startup Office Management Systems Business \/ Marketing New Trends In SEO &#038; Analytics Media \/&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":[],"_links":{"self":[{"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/pages\/796"}],"collection":[{"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/comments?post=796"}],"version-history":[{"count":2,"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/pages\/796\/revisions"}],"predecessor-version":[{"id":7357,"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/pages\/796\/revisions\/7357"}],"wp:attachment":[{"href":"https:\/\/startit.qodeinteractive.com\/elementor\/wp-json\/wp\/v2\/media?parent=796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}